{"id":25036,"date":"2017-09-28T07:17:49","date_gmt":"2017-09-28T07:17:49","guid":{"rendered":"http:\/\/localhost:8888\/?page_id=25036\/"},"modified":"2026-03-03T16:26:18","modified_gmt":"2026-03-03T16:26:18","slug":"flair-angel","status":"publish","type":"page","link":"https:\/\/barsolutions.ro\/en\/flair-angel\/","title":{"rendered":"Flair Angel"},"content":{"rendered":"[vc_row disable_element=&#8221;yes&#8221;][vc_column][vc_single_image image=&#8221;25736&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;fadeIn&#8221;][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1520255953576{margin-bottom: 0px !important;border-bottom-width: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;text-justify&#8221;]\n<div class=\"page\" title=\"Page 18\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Flair Angel is bar opened on September 8, 2011 inside the Bragadiru Palace, <a href=\"https:\/\/www.google.com\/maps\/place\/Palatul+Bragadiru,+Calea+Rahovei+147-153,+Bucure%C8%99ti+050892\/@44.4214931,26.08495,17z\/data=!3m1!4b1!4m5!3m4!1s0x40b1ff72e80648f5:0x368f81e8051f2714!8m2!3d44.4215037!4d26.0871613\" target=\"_blank\" rel=\"noopener\">Calea Rahovei\/ 147-153, Sector 5, Bucharest<\/a><\/p>\n<p>The bar wears the name of the former Exquisite Bar Solutions team member, Bogdan Costiniu ( deceased 2010 ), who introduced himself in national and international bartending competitions, and also flair shows with the stage name \u201c Flair Angel \u201d<\/p>\n<p>The description spirit \/ sugar \/ water \/ bitter, comes from the first printed definition of the term \u201ccocktail\u201d, who appeared in the New York gazette \u201c The Balance and Columbian Repository \u201d on May 13th, 1806.<\/p>\n<div class=\"page\" title=\"Page 18\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\u201cCock-tail is a stimulating liquor, composed of spirits of any kind, sugar, water, and bitters\u2014it is vulgarly called a bittered sling&#8230;\u201d<\/p>\n<div class=\"page\" title=\"Page 18\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Flair Angel is the Set Standard for the Hospitality Industry in Romania, also being is the business card of Exquisite Bar Solutions Professional Bartending Agency.<br \/>\nFind out why, every bartender in the Flair Angel Team are internationally awarded, and why the drinks that they make are unique!<br \/>\nFlair Angel Bar!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 904px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 180px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(255,255,255, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: 0px 0px 0px #888888;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }        @media only screen and (min-width: 480px) {      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {        transition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0:hover {        -ms-transform: scale(1.1);        -webkit-transform: scale(1.1);        transform: scale(1.1);      }    }          #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 50%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #CCCCCC;      font-family: segoe ui;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: 0px 0px 0px #888888;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #CCCCCC;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/en\/wp-json\/wp\/v2\/pages\/25036\"         data-lightbox-url=\"https:\/\/barsolutions.ro\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=3&#038;tag=0&#038;theme_id=1&#038;shortcode_id=3&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Fen%2Fwp-json%2Fwp%2Fv2%2Fpages%2F25036\"         data-gallery-id=\"3\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"3\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"3\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/barsolutions.ro\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"180\"         data-bwg=\"0\"         data-gallery-id=\"3\"         data-lightbox-url=\"https:\/\/barsolutions.ro\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=3&amp;tag=0&amp;theme_id=1&amp;shortcode_id=3&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Fen%2Fwp-json%2Fwp%2Fv2%2Fpages%2F25036\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"85\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/11.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"85\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/11.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/11.jpg?bwg=1772555029\"                   alt=\"11\"                   title=\"11\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"86\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/13.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"86\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/13.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/13.jpg?bwg=1772555029\"                   alt=\"13\"                   title=\"13\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"87\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/12.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"87\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/12.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/12.jpg?bwg=1772555029\"                   alt=\"12\"                   title=\"12\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"88\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/15.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"88\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/15.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/15.jpg?bwg=1772555029\"                   alt=\"15\"                   title=\"15\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"89\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/14.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"89\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/14.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/14.jpg?bwg=1772555029\"                   alt=\"14\"                   title=\"14\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"90\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/16.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"90\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/16.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/16.jpg?bwg=1772555029\"                   alt=\"16\"                   title=\"16\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"91\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/01.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"91\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/01.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/01.jpg?bwg=1772555029\"                   alt=\"01\"                   title=\"01\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"92\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/02.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"92\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/02.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/02.jpg?bwg=1772555029\"                   alt=\"02\"                   title=\"02\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"93\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/04.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"93\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/04.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/04.jpg?bwg=1772555029\"                   alt=\"04\"                   title=\"04\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"94\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/03.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"94\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/03.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/03.jpg?bwg=1772555029\"                   alt=\"03\"                   title=\"03\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"95\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/05.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"95\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/05.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/05.jpg?bwg=1772555029\"                   alt=\"05\"                   title=\"05\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"96\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/06.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"96\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/06.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/06.jpg?bwg=1772555029\"                   alt=\"06\"                   title=\"06\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"97\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/07.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"97\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/07.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/07.jpg?bwg=1772555029\"                   alt=\"07\"                   title=\"07\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"98\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/09.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"98\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/09.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/09.jpg?bwg=1772555029\"                   alt=\"09\"                   title=\"09\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"99\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/08.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"99\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/08.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/08.jpg?bwg=1772555029\"                   alt=\"08\"                   title=\"08\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"100\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/10.jpg?bwg=1772555029\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"100\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/10.jpg?bwg=1772555029\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/10.jpg?bwg=1772555029\"                   alt=\"10\"                   title=\"10\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"84\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/-3008-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"84\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/-3008-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/-3008-min.jpg\"                   alt=\"-3008-min\"                   title=\"-3008-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"83\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/-2977-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"83\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/-2977-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/-2977-min.jpg\"                   alt=\"-2977-min\"                   title=\"-2977-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"82\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-63-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"82\"                   data-width=\"500.00\"                   data-height=\"332.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-63-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-63-min.jpg\"                   alt=\"Image-63-min\"                   title=\"Image-63-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"81\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-70-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"81\"                   data-width=\"332.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-70-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-70-min.jpg\"                   alt=\"Image-70-min\"                   title=\"Image-70-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"80\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/-3028-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"80\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/-3028-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/-3028-min.jpg\"                   alt=\"-3028-min\"                   title=\"-3028-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"79\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-09-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"79\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-09-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-09-min.jpg\"                   alt=\"Image-09-min\"                   title=\"Image-09-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"78\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-62-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"78\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-62-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-62-min.jpg\"                   alt=\"Image-62-min\"                   title=\"Image-62-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"77\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-11-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"77\"                   data-width=\"500.00\"                   data-height=\"333.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-11-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-11-min.jpg\"                   alt=\"Image-11-min\"                   title=\"Image-11-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"76\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-16-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"76\"                   data-width=\"332.00\"                   data-height=\"500.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-16-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-16-min.jpg\"                   alt=\"Image-16-min\"                   title=\"Image-16-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"75\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/Image-71_copy-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"75\"                   data-width=\"500.00\"                   data-height=\"336.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-71_copy-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/Image-71_copy-min.jpg\"                   alt=\"Image-71 copy-min\"                   title=\"Image-71 copy-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"74\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/fotografii-flair-angel-high-res-7-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"74\"                   data-width=\"500.00\"                   data-height=\"332.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-7-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-7-min.jpg\"                   alt=\"fotografii-flair-angel-high-res-7-min\"                   title=\"fotografii-flair-angel-high-res-7-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"73\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/fotografii-flair-angel-high-res-38-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"73\"                   data-width=\"500.00\"                   data-height=\"332.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-38-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-38-min.jpg\"                   alt=\"fotografii-flair-angel-high-res-38-min\"                   title=\"fotografii-flair-angel-high-res-38-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"72\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/fotografii-flair-angel-high-res-64-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"72\"                   data-width=\"500.00\"                   data-height=\"332.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-64-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-64-min.jpg\"                   alt=\"fotografii-flair-angel-high-res-64-min\"                   title=\"fotografii-flair-angel-high-res-64-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"71\" href=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/fotografii-flair-angel-high-res-93-min.jpg\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"71\"                   data-width=\"500.00\"                   data-height=\"332.00\"                   data-src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-93-min.jpg\"                   src=\"https:\/\/barsolutions.ro\/wp-content\/uploads\/photo-gallery\/thumb\/fotografii-flair-angel-high-res-93-min.jpg\"                   alt=\"fotografii-flair-angel-high-res-93-min\"                   title=\"fotografii-flair-angel-high-res-93-min\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: segoe ui;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #000000;          opacity: 0.70;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"774176867\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1520262132713{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1520256978421{margin-bottom: 45px !important;}&#8221;]\n<h3 class=\"title-h3\" style=\"text-align: center;\">Our Location<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1520256025276{margin-bottom: 0px !important;}&#8221;]<div id=\"wpgmza_map\" class=\"wpgmza_map\" data-settings='{\"id\":\"1\",\"map_title\":\"Exquisite\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"44.421529\",\"map_start_lng\":\"26.087131\",\"map_start_location\":\"44.421528616018705,26.087131193780476\",\"map_start_zoom\":\"15\",\"default_marker\":\"0\",\"type\":\"1\",\"alignment\":\"2\",\"directions_enabled\":\"1\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"1\",\"dbox_width\":\"100\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"\\\\%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"1\",\"ugm_access\":\"0\",\"order_markers_by\":\"1\",\"order_markers_choice\":\"2\",\"show_user_location\":\"0\",\"default_to\":\"\",\"other_settings\":{\"store_locator_enabled\":2,\"store_locator_distance\":2,\"store_locator_default_radius\":\"10\",\"store_locator_not_found_message\":\"No results found in this location. Please try again.\",\"store_locator_bounce\":1,\"store_locator_query_string\":\"Cod po\\u0219tal \\\/ Adres\\u0103:\",\"store_locator_default_address\":\"\",\"wpgmza_store_locator_restrict\":\"\",\"map_max_zoom\":\"1\",\"transport_layer\":0,\"wpgmza_theme_data\":\"[{\\\\\\\"featureType\\\\\\\":\\\\\\\"landscape\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"saturation\\\\\\\":-100},{\\\\\\\"lightness\\\\\\\":65},{\\\\\\\"visibility\\\\\\\":\\\\\\\"on\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"poi\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"saturation\\\\\\\":-100},{\\\\\\\"lightness\\\\\\\":51},{\\\\\\\"visibility\\\\\\\":\\\\\\\"simplified\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"road.highway\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"saturation\\\\\\\":-100},{\\\\\\\"visibility\\\\\\\":\\\\\\\"simplified\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"road.arterial\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"saturation\\\\\\\":-100},{\\\\\\\"lightness\\\\\\\":30},{\\\\\\\"visibility\\\\\\\":\\\\\\\"on\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"road.local\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"saturation\\\\\\\":-100},{\\\\\\\"lightness\\\\\\\":40},{\\\\\\\"visibility\\\\\\\":\\\\\\\"on\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"transit\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"saturation\\\\\\\":-100},{\\\\\\\"visibility\\\\\\\":\\\\\\\"simplified\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"administrative.province\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"visibility\\\\\\\":\\\\\\\"off\\\\\\\"}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"water\\\\\\\",\\\\\\\"elementType\\\\\\\":\\\\\\\"labels\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"visibility\\\\\\\":\\\\\\\"on\\\\\\\"},{\\\\\\\"lightness\\\\\\\":-25},{\\\\\\\"saturation\\\\\\\":-100}]},{\\\\\\\"featureType\\\\\\\":\\\\\\\"water\\\\\\\",\\\\\\\"elementType\\\\\\\":\\\\\\\"geometry\\\\\\\",\\\\\\\"stylers\\\\\\\":[{\\\\\\\"hue\\\\\\\":\\\\\\\"#ffff00\\\\\\\"},{\\\\\\\"lightness\\\\\\\":-25},{\\\\\\\"saturation\\\\\\\":-97}]}]\",\"wpgmza_theme_selection\":3,\"wpgmza_show_points_of_interest\":1}}' data-map-id='1' Data-maps-engine='' data-shortcode-attributes='{\"id\":\"1\"}' style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\"><\/div>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row disable_element=&#8221;yes&#8221;][vc_column][vc_single_image image=&#8221;25736&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;fadeIn&#8221;][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1520255953576{margin-bottom: 0px !important;border-bottom-width: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;text-justify&#8221;] Flair Angel is bar opened on September 8, 2011 inside the Bragadiru&#8230;<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25036","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/pages\/25036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/comments?post=25036"}],"version-history":[{"count":2,"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/pages\/25036\/revisions"}],"predecessor-version":[{"id":26392,"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/pages\/25036\/revisions\/26392"}],"wp:attachment":[{"href":"https:\/\/barsolutions.ro\/en\/wp-json\/wp\/v2\/media?parent=25036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}